{"id":3360,"date":"2017-04-25T17:07:18","date_gmt":"2017-04-25T20:07:18","guid":{"rendered":"http:\/\/www.periodicoelapogeo.com.ar\/site\/?p=3360"},"modified":"2017-04-25T17:09:29","modified_gmt":"2017-04-25T20:09:29","slug":"club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires","status":"publish","type":"post","link":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/","title":{"rendered":"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires"},"content":{"rendered":"<h3>La instituci\u00f3n deportiva gan\u00f3 el Torneo Provincial de B\u00e1squet y estall\u00f3 la locura.<\/h3>\n<p>El primer fin de semana de abril se realiz\u00f3 el Final Four con los mejores cuatro equipos del Torneo Provincial de Clubes de b\u00e1squet edici\u00f3n 2016\/17. El campe\u00f3n fue Presidente Derqui, mientras que Independiente de Zarate fue el subcampe\u00f3n. Ambos ascienden al Torneo Federal.<\/p>\n<p>Desde 1953 cuando se compraron los terrenos de la mano de aquella comisi\u00f3n fundante y Don Carlos Barrios lleg\u00f3 con la noticia de la posibilidad de estar para siempre bien cerquita de la estaci\u00f3n. \u00a1Cu\u00e1nto ha logrado el Club <u>P<\/u>residente Derqui!<\/p>\n<blockquote><p><em>\u201cLa clasificaci\u00f3n al Cuadrangular Final del Provincial de Clubes de Buenos Aires abri\u00f3 la posibilidad de realizar el mini certamen en nuestra sede por derecho deportivo. El Rojinegro fue el n\u00famero 1 de la fase regular y por eso tiene la prioridad para ser el anfitri\u00f3n de la definici\u00f3n que tiene en juego, adem\u00e1s del t\u00edtulo, 2 ascensos al Torneo Federal 2017\/18.\u201d<\/em><\/p><\/blockquote>\n<p>As\u00ed arranc\u00f3 el sue\u00f1o.<\/p>\n<p>La cuesti\u00f3n es que se hizo historia y el latir de corazones exaltados, sacudi\u00f3 las columnas del estadio para alojarse para siempre entre las p\u00e1ginas mejores que se han escrito.<\/p>\n<p>El esfuerzo y la pasi\u00f3n de barrio quedar\u00e1n grabados en la mirada de los chicos, como antes de sus dirigentes, todos criados entre las paredes de la gloriosa instituci\u00f3n.<\/p>\n<p>Desde las gradas no faltaron las voces de aliento en los tres d\u00edas de competencias. Un abrazo de gol con la bendici\u00f3n de los mayores acompa\u00f1\u00f3 con orgullo el festejo de los protagonistas de hoy.<\/p>\n<p>Alejandro Irigoyen, Nicol\u00e1s Medina, Nicol\u00e1s Tabarez, Juan Ignacio Baquero, Maximiliano Guti\u00e9rrez, Nicol\u00e1s Suarez, Ignacio Suarez, Juan Ignacio Bello, Nicol\u00e1s Gallo, Sebasti\u00e1n D\u00edaz. Juveniles: Nicol\u00e1s Henr\u00edquez, \u00c1lvaro Mendoza, Juan Mendoza, Rafael Acosta, Nehuen Alvite, Gonzalo Floriani, Cristian L\u00f3pez. Dt: Marcelo Asturiano. Asistentes: Federico Mart\u00ednez, Juan Pablo Michaud. Preparador f\u00edsico: Santiago Sicardi. Planillero: Horacio Reyes.<\/p>\n<p>Y cuando se cuente la historia ma\u00f1ana, sus nombres\u00a0 tendr\u00e1n un lugar en la gloria, que no es otra que junto a los nombres del primer equipo de b\u00e1squet: Armando Borsani, el gato Zanatta, el negro Zambrano, Carlos Basualdo, el gordo Reynoso, Hugo Pozzi, los hermanos Wechenfeller, el gordo Rodi, despu\u00e9s llegar\u00edan Quique Basterrica, los hermanos Estrada, Menguchi y Norverto Crocenzi.<\/p>\n<p>La historia sigue y seguir\u00e1, club de barrio que ha superado todas las expectativas. \u00a0La ciudad te saluda y los vecinos tambi\u00e9n.<\/p>\n<p>por Victor Korpivsek<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La instituci\u00f3n deportiva gan\u00f3 el Torneo Provincial de B\u00e1squet y estall\u00f3 la locura. El primer fin de semana de abril se realiz\u00f3 el Final Four con los mejores cuatro equipos&hellip; <\/p>\n","protected":false},"author":1,"featured_media":3361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,1],"tags":[769,231,767,7,768],"class_list":["post-3360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal","category-sin-categoria","tag-basquet","tag-deporte","tag-deporte-es-integracion","tag-derqui","tag-final-four"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires - Peri\u00f3dico EL APOGEO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires - Peri\u00f3dico EL APOGEO\" \/>\n<meta property=\"og:description\" content=\"La instituci\u00f3n deportiva gan\u00f3 el Torneo Provincial de B\u00e1squet y estall\u00f3 la locura. El primer fin de semana de abril se realiz\u00f3 el Final Four con los mejores cuatro equipos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico EL APOGEO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Peridico-El-Apogeo-348111616395\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-25T20:07:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-25T20:09:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-content\/uploads\/2017\/04\/deporte-es-integracion-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elapogeodiario\" \/>\n<meta name=\"twitter:site\" content=\"@elapogeodiario\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#\\\/schema\\\/person\\\/5a441efd2553122a396c5c899b86cc56\"},\"headline\":\"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires\",\"datePublished\":\"2017-04-25T20:07:18+00:00\",\"dateModified\":\"2017-04-25T20:09:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/\"},\"wordCount\":444,\"publisher\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/deporte-es-integracion-1.jpg\",\"keywords\":[\"B\u00e1squet\",\"deporte\",\"deporte es integraci\u00f3n\",\"Derqui\",\"Final Four\"],\"articleSection\":[\"Principal\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/\",\"url\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/\",\"name\":\"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires - Peri\u00f3dico EL APOGEO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/deporte-es-integracion-1.jpg\",\"datePublished\":\"2017-04-25T20:07:18+00:00\",\"dateModified\":\"2017-04-25T20:09:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/deporte-es-integracion-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/deporte-es-integracion-1.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Foto gentileza Ale Irigoyen. El segundo fin de semana de abril la historia se escribi\u00f3 en Derqui. Felicitaciones muchachos.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/\",\"name\":\"Peri\u00f3dico EL APOGEO\",\"description\":\"En Derqui, Del Viso, Mor\u00f3n y Pilar\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#organization\",\"name\":\"Peri\u00f3dico EL APOGEO\",\"url\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/apogeo_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/apogeo_logo.jpg\",\"width\":400,\"height\":400,\"caption\":\"Peri\u00f3dico EL APOGEO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Peridico-El-Apogeo-348111616395\\\/\",\"https:\\\/\\\/x.com\\\/elapogeodiario\",\"https:\\\/\\\/instagram.com\\\/elapogeodiario\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/#\\\/schema\\\/person\\\/5a441efd2553122a396c5c899b86cc56\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/704de488fa2b0c8e44313319265e8bb9487c4e07ed3378c63f7d4699c1ac302f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/704de488fa2b0c8e44313319265e8bb9487c4e07ed3378c63f7d4699c1ac302f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/704de488fa2b0c8e44313319265e8bb9487c4e07ed3378c63f7d4699c1ac302f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.periodicoelapogeo.com.ar\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires - Peri\u00f3dico EL APOGEO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/","og_locale":"es_ES","og_type":"article","og_title":"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires - Peri\u00f3dico EL APOGEO","og_description":"La instituci\u00f3n deportiva gan\u00f3 el Torneo Provincial de B\u00e1squet y estall\u00f3 la locura. El primer fin de semana de abril se realiz\u00f3 el Final Four con los mejores cuatro equipos&hellip;","og_url":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/","og_site_name":"Peri\u00f3dico EL APOGEO","article_publisher":"https:\/\/www.facebook.com\/Peridico-El-Apogeo-348111616395\/","article_published_time":"2017-04-25T20:07:18+00:00","article_modified_time":"2017-04-25T20:09:29+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-content\/uploads\/2017\/04\/deporte-es-integracion-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@elapogeodiario","twitter_site":"@elapogeodiario","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/#article","isPartOf":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/"},"author":{"name":"admin","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#\/schema\/person\/5a441efd2553122a396c5c899b86cc56"},"headline":"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires","datePublished":"2017-04-25T20:07:18+00:00","dateModified":"2017-04-25T20:09:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/"},"wordCount":444,"publisher":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#organization"},"image":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-content\/uploads\/2017\/04\/deporte-es-integracion-1.jpg","keywords":["B\u00e1squet","deporte","deporte es integraci\u00f3n","Derqui","Final Four"],"articleSection":["Principal"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/","url":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/","name":"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires - Peri\u00f3dico EL APOGEO","isPartOf":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/#primaryimage"},"image":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-content\/uploads\/2017\/04\/deporte-es-integracion-1.jpg","datePublished":"2017-04-25T20:07:18+00:00","dateModified":"2017-04-25T20:09:29+00:00","breadcrumb":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/#primaryimage","url":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-content\/uploads\/2017\/04\/deporte-es-integracion-1.jpg","contentUrl":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-content\/uploads\/2017\/04\/deporte-es-integracion-1.jpg","width":1280,"height":960,"caption":"Foto gentileza Ale Irigoyen. El segundo fin de semana de abril la historia se escribi\u00f3 en Derqui. Felicitaciones muchachos."},{"@type":"BreadcrumbList","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/club-presidente-derqui-campeon-de-la-provincia-de-buenos-aires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.periodicoelapogeo.com.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Club Presidente Derqui campe\u00f3n de la Provincia de Buenos Aires"}]},{"@type":"WebSite","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#website","url":"https:\/\/www.periodicoelapogeo.com.ar\/site\/","name":"Peri\u00f3dico EL APOGEO","description":"En Derqui, Del Viso, Mor\u00f3n y Pilar","publisher":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.periodicoelapogeo.com.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#organization","name":"Peri\u00f3dico EL APOGEO","url":"https:\/\/www.periodicoelapogeo.com.ar\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-content\/uploads\/2023\/03\/apogeo_logo.jpg","contentUrl":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-content\/uploads\/2023\/03\/apogeo_logo.jpg","width":400,"height":400,"caption":"Peri\u00f3dico EL APOGEO"},"image":{"@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Peridico-El-Apogeo-348111616395\/","https:\/\/x.com\/elapogeodiario","https:\/\/instagram.com\/elapogeodiario\/"]},{"@type":"Person","@id":"https:\/\/www.periodicoelapogeo.com.ar\/site\/#\/schema\/person\/5a441efd2553122a396c5c899b86cc56","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/704de488fa2b0c8e44313319265e8bb9487c4e07ed3378c63f7d4699c1ac302f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/704de488fa2b0c8e44313319265e8bb9487c4e07ed3378c63f7d4699c1ac302f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/704de488fa2b0c8e44313319265e8bb9487c4e07ed3378c63f7d4699c1ac302f?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.periodicoelapogeo.com.ar\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/posts\/3360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/comments?post=3360"}],"version-history":[{"count":1,"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/posts\/3360\/revisions"}],"predecessor-version":[{"id":3362,"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/posts\/3360\/revisions\/3362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/media\/3361"}],"wp:attachment":[{"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/media?parent=3360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/categories?post=3360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.periodicoelapogeo.com.ar\/site\/wp-json\/wp\/v2\/tags?post=3360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}